{"id":20385,"date":"2021-02-01T10:16:50","date_gmt":"2021-02-01T09:16:50","guid":{"rendered":"https:\/\/www.escalade.pro\/news\/?p=20385"},"modified":"2021-04-30T14:33:01","modified_gmt":"2021-04-30T12:33:01","slug":"entrainement-covid-pompes-tractions-semaine-3","status":"publish","type":"post","link":"https:\/\/www.escalade.pro\/news\/entrainement-covid-pompes-tractions-semaine-3\/","title":{"rendered":"Entrainement COVID \u00e0 la maison, pompes et tractions, semaine 3\/4"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-20387 size-thumbnail\" src=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/training-1-150x150.jpg\" alt=\"entrainement escalade \u00e0 domicile\" width=\"150\" height=\"150\" srcset=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/training-1-150x150.jpg 150w, https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/training-1-300x300.jpg 300w, https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/training-1-550x550.jpg 550w, https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/training-1-200x200.jpg 200w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong>On se retrouve pour la troisi\u00e8me semaine d&rsquo;entrainement \u00e0 domicile<\/strong> et on continue \u00e0 avancer avec le sourire. Apr\u00e8s les <a href=\"https:\/\/www.escalade.pro\/news\/entrainement-maison-semaine-1-4\/\">\u00e9tirements et les muscles antagonistes en premi\u00e8re semaine<\/a>, le <a href=\"https:\/\/www.escalade.pro\/news\/entrainement-covid-maison-semaine-2-4\/\">gainage<\/a> en deuxi\u00e8me semaine, <strong>nous allons d\u00e9sormais nous attaquer aux pompes et tractions<\/strong>.<br \/>\n<strong>Ne partez pas en courant \u00e0 la lecture de ces premi\u00e8res lignes! Certes il va falloir \u00eatre pr\u00eat \u00e0 forcer, mais je vais vous proposer plusieurs niveaux de difficult\u00e9. En \u00e9tant positif et patient, vous allez progresser physiquement et vous f\u00e9liciterez de votre engagement \u00e0 la reprise de la grimpe.<\/strong><\/p>\n<p>Concernant les pompes, il serait pr\u00e9f\u00e9rable pour vos poignets et la sp\u00e9cificit\u00e9 de l&rsquo;exercice d&rsquo;utiliser des <a href=\"https:\/\/www.google.com\/search?q=poign%C3%A9e+push+up&amp;tbm=isch&amp;hl=fr&amp;sa=X&amp;ved=2ahUKEwiyy9rN6sDuAhUMgM4BHcuGDdYQBXoECAEQLQ&amp;biw=1583&amp;bih=789\" target=\"_blank\" rel=\"noopener\">poign\u00e9es<\/a>. Mais on peut faire sans, avec les mains au sol. Pour les tractions, l&rsquo;id\u00e9al est d&rsquo;avoir une barre \u00e0 tractions. Tout autre support tels qu&rsquo;une marche d&rsquo;escalier ou un rebord de balcon pourra faire l&rsquo;affaire.<\/p>\n<hr \/>\n<h6><span style=\"color: #ff0000;\"><u>AVERTISSEMENT 1<\/u><\/span><\/h6>\n<p><span style=\"color: #ff0000;\">Echauffez-vous avant de commencer la s\u00e9ance, avec des mouvements au sol mobilisant une \u00e0 une les articulations (voir par exemple cette <a style=\"color: #ff0000;\" href=\"https:\/\/www.youtube.com\/watch?v=c555QL4z1O4\" target=\"_blank\" rel=\"noopener\"><u>vid\u00e9o<\/u><\/a>). Passez ensuite \u00e0 quelques exercices de la <a style=\"color: #ff0000;\" href=\"https:\/\/www.escalade.pro\/news\/entrainement-maison-semaine-1-4\/\"><u>semaine 1<\/u><\/a> puis terminez par quelques pompes et tractions en douceur.<\/span><\/p>\n<p><span style=\"color: #ff0000;\"><u>Attention \u00e0 votre placement et \u00e0 la qualit\u00e9 des mouvements (s&rsquo;entrainer \u00e0 2 si possible c&rsquo;est mieux):<\/u><\/span><br \/>\n<span style=\"color: #ff0000;\">&#8211; Pour les pompes, NE CAMBREZ PAS LE BAS DU DOS, en serrant l\u00e9g\u00e8rement les fesses et les abdos. Quelque soit la position de vos coudes, gardez LES EPAULES BASSES, rapprochez vos omoplates lors de la descente. <\/span><br \/>\n<span style=\"color: #ff0000;\">&#8211; Pour les tractions, gardez \u00e9galement les \u00e9paules basses, mais aussi les coudes le long du corps en montant. <\/span><\/p>\n<p><span style=\"color: #ff0000;\">Arr\u00eatez imm\u00e9diatement si la qualit\u00e9 du geste se d\u00e9grade, si une douleur articulaire ou musculaire, autre que la fatigue, apparait. Oh que j&rsquo;aime pas \u00e9crire des choses si vagues et impr\u00e9cises&#8230; vivement qu&rsquo;on est le droit de grimper (pour vous et moi) et travailler (pour moi) \u00e0 nouveau!<\/span><\/p>\n<hr \/>\n<h6><u>Pompes<\/u><\/h6>\n<p><strong>Voici 3 positions \u00e0 utiliser selon votre niveau:<br \/>\n&#8211; Si repos\u00e9 vous faites de 0 \u00e0 5 pompes maximum. R\u00e9alisez les s\u00e9ries de pompes sur les genoux.<br \/>\n&#8211; Si vous \u00eates capable de faire entre 5 et 30 pompes, travaillez sur la position classique de pompe.<br \/>\n&#8211; Si vous pouvez effectuer plus de 30 pompes, sur\u00e9levez vos pieds, en les pla\u00e7ant sur une chaise par exemple (ne pas cambrer, garder les \u00e9paules basses, pas facile!).<\/strong><\/p>\n<p><strong>Faites 5 \u00e0 10 s\u00e9ries de 3 \u00e0 12 pompes, avec 1 \u00e0 4 minutes de repos.<\/strong><\/p>\n<p><u>Un exemple facile:<\/u><br \/>\n5 fois 3 pompes avec 4 minutes de repos.<br \/>\n<u>Un exemple difficile:<\/u><br \/>\n6 fois 12 pompes avec 1 minute de repos.<\/p>\n<div id='gallery-1' class='gallery galleryid-20385 gallery-columns-3 gallery-size-colormag-featured-image'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a title=\"entrainement escalade\" href='https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/P1020855.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/P1020855-800x445.jpg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"entrainement escalade\" aria-describedby=\"gallery-1-20454\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-20454'>\n\t\t\t\tPompes cambr\u00e9es (monter un peu les fesses, serrer le ventre).\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a title=\"entrainement escalade\" href='https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/P1020856.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/P1020856-800x445.jpg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"entrainement escalade\" aria-describedby=\"gallery-1-20455\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-20455'>\n\t\t\t\tPompes avec \u00e9paules trop hautes.\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a title=\"entrainement escalade\" href='https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/P1020858.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/P1020858-800x445.jpg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"entrainement escalade\" aria-describedby=\"gallery-1-20456\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-20456'>\n\t\t\t\tPompes sur les genoux (plus facile).\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<hr \/>\n<h6><u>Tractions<\/u><\/h6>\n<p><span style=\"color: #ff0000;\">Pour la plupart de vos s\u00e9ries, ne redescendez pas jusqu&rsquo;en bas de la traction (arr\u00eatez la descente avant la position coude tendu).<\/span> <\/p>\n<p><strong><span style=\"text-decoration: underline;\">Si vous n\u2019\u00eates pas capable de faire une traction :<\/span><\/strong><br \/>\n-Utilisez un \u00e9lastique, attach\u00e9 \u00e0 la barre, dans lequel vous passez vos pieds pour vous all\u00e9ger.<br \/>\n-Ou utilisez une chaise pour vous all\u00e9ger \u00e9galement.<br \/>\n-Ou prenez une impulsion avec les jambes depuis le sol pour d\u00e9marrer la traction plus facilement.<\/p>\n<p><span style=\"color: #ff0000;\">N\u2019h\u00e9sitez pas \u00e0 utiliser ces artifices, assumez et vous vous am\u00e9liorerez. Mais si vous n\u2019avez pas\/plus assez de force pour contr\u00f4ler la descente, utilisez une chaise ou arr\u00eatez. Chacun son niveau, son rythme de progression et son m\u00e9rite.<\/span><\/p>\n<p><strong>Faites 5 \u00e0 10 s\u00e9ries de 2 \u00e0 12 tractions, avec 1 \u00e0 4 minutes de repos.<\/strong><\/p>\n<p><u>Un exemple facile:<\/u><br \/>\n5 fois 2 tractions avec 4 minutes de repos.<br \/>\n<u>Un exemple tr\u00e8s difficile:<\/u><br \/>\n6 fois 12 tractions avec 1 minute de repos.<\/p>\n<div id='gallery-2' class='gallery galleryid-20385 gallery-columns-3 gallery-size-colormag-featured-image'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a title=\"entrainement escalade\" href='https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/P1020859.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/P1020859-800x445.jpg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"entrainement escalade\" aria-describedby=\"gallery-2-20458\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-2-20458'>\n\t\t\t\tTraction avec \u00e9lastique pour s&rsquo;all\u00e9ger.\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a title=\"entrainement escalade \u00e0 domicile\" href='https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/P1020862.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"798\" height=\"445\" src=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/P1020862-798x445.jpg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"entrainement escalade \u00e0 domicile\" aria-describedby=\"gallery-2-20459\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-2-20459'>\n\t\t\t\tTractions avec pieds sur une chaise.\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a title=\"entrainement escalade\" href='https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/P1020857.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/P1020857-800x445.jpg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"entrainement escalade\" aria-describedby=\"gallery-2-20460\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-2-20460'>\n\t\t\t\tCoudes trop \u00e9cart\u00e9s, \u00e9paules hautes.\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<hr \/>\n<h6><u>Variantes<\/u><\/h6>\n<p><strong>Enorm\u00e9ment de variantes sont possibles pour ces exercices et s\u00e9ries basiques.<\/strong> <\/p>\n<p>En voici quelques unes:<br \/>\n&#8211; Alterner pompes et tractions.<br \/>\n&#8211; Fonctionner en pyramide (par exemple 2 tractions, puis 4, puis 6, &#8230; et redescendre quand on est au maximum).<br \/>\n&#8211; Changer la position des mains (plus ou moins \u00e9cart\u00e9es, paume de main vers soi -supination ou vers l&rsquo;avant-pronation pour les tractions).<br \/>\n&#8211; Varier les \u00ab\u00a0r\u00e9gimes de contraction musculaire\u00a0\u00bb (promis j&rsquo;arr\u00eate les gros mots).<br \/>\nPar exemple descendre la traction ou la pompe doucement, ou encore rester 3 secondes en blocage en milieu, fin ou d\u00e9but de mouvement.<br \/>\n&#8211; S&rsquo;entrainer et sourire apr\u00e8s 18h00.<\/p>\n<hr \/>\n<h6><u>Organisation<\/u><\/h6>\n<p><strong>Prenez un minimum de 48 heures de repos entre chaque s\u00e9ance.<\/strong> Surtout qu&rsquo;au d\u00e9but les courbatures peuvent \u00eatre m\u00e9chantes. Dans ce cas 72 heures ne seront pas un luxe. Cela vous laisse ainsi du temps pour <strong>reprendre les exercices des semaines <a href=\"https:\/\/www.escalade.pro\/news\/entrainement-maison-semaine-1-4\/\">1<\/a> et <a href=\"https:\/\/www.escalade.pro\/news\/entrainement-covid-maison-semaine-2-4\/\">2<\/a>, ils sont tr\u00e8s importants!<\/strong><br \/>\n<strong>N&rsquo;oubliez pas de noter vos s\u00e9ances afin d&rsquo;avoir des rep\u00e8res de progression et de fatigue.<\/strong><\/p>\n<hr \/>\n<p><strong>On se retrouve le lundi 8 f\u00e9vrier pour la 4eme semaine d&rsquo;entrainement. Nous travaillerons la r\u00e9sistance et la conti sur une poutre<\/strong>&#8230; pour ceux qui en poss\u00e8dent une.<br \/>\n<strong>Soyez forts, positifs, valorisez vos progr\u00e8s<\/strong>, et n&rsquo;h\u00e9sitez pas si vous avez des questions!<\/p>\n<hr \/>\n<h6><span style=\"color: #ff0000;\"><u>AVERTISSEMENT 2<\/u><\/span><\/h6>\n<p><span style=\"color: #ff0000;\">Les photos sont de mauvaise qualit\u00e9, car moi non plus je n\u2019ai pas acc\u00e8s \u00e0 une salle d\u2019entrainement avec de l\u2019\u00e9clairage et de l\u2019espace depuis des mois.&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>On se retrouve pour la troisi\u00e8me semaine d\u2019entrainement \u00e0 domicile et on continue \u00e0 progresser. Apr\u00e8s les \u00e9tirements et les muscles antagonistes en premi\u00e8re semaine, le gainage en deuxi\u00e8me semaine, nous allons d\u00e9sormais nous attaquer aux pompes et tractions.<\/p>\n","protected":false},"author":1,"featured_media":20387,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6,4],"tags":[188,202,31,17],"class_list":["post-20385","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrainement-escalade","category-escalade","tag-covid","tag-domicile","tag-entrainement","tag-escalade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entrainement COVID \u00e0 la maison, pompes, tractions, sem 3 - Grimpisme<\/title>\n<meta name=\"description\" content=\"Troisi\u00e8me semaine d\u2019entrainement COVID \u00e0 domicile. Apr\u00e8s les \u00e9tirements, les antagonistes, le gainage, place aux pompes et tractions.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.escalade.pro\/news\/entrainement-covid-pompes-tractions-semaine-3\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrainement COVID \u00e0 la maison, pompes, tractions, sem 3 - Grimpisme\" \/>\n<meta property=\"og:description\" content=\"Troisi\u00e8me semaine d\u2019entrainement COVID \u00e0 domicile. Apr\u00e8s les \u00e9tirements, les antagonistes, le gainage, place aux pompes et tractions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.escalade.pro\/news\/entrainement-covid-pompes-tractions-semaine-3\/\" \/>\n<meta property=\"og:site_name\" content=\"L&#039;Arqu\u00e9e Libre - Fred Vionnet entraineur\/moniteur escalade\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grimpisme\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/fredCaillouXvionnet\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-01T09:16:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-30T12:33:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/training-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"924\" \/>\n\t<meta property=\"og:image:height\" content=\"1100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fred Vionnet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fred Vionnet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/entrainement-covid-pompes-tractions-semaine-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/entrainement-covid-pompes-tractions-semaine-3\\\/\"},\"author\":{\"name\":\"Fred Vionnet\",\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/#\\\/schema\\\/person\\\/e0e0520aa48cfda56ae5406c2fe2caeb\"},\"headline\":\"Entrainement COVID \u00e0 la maison, pompes et tractions, semaine 3\\\/4\",\"datePublished\":\"2021-02-01T09:16:50+00:00\",\"dateModified\":\"2021-04-30T12:33:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/entrainement-covid-pompes-tractions-semaine-3\\\/\"},\"wordCount\":830,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/entrainement-covid-pompes-tractions-semaine-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/training-1.jpg\",\"keywords\":[\"covid\",\"domicile\",\"entrainement\",\"escalade\"],\"articleSection\":[\"Conseils entrainement escalade\",\"Escalade\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.escalade.pro\\\/news\\\/entrainement-covid-pompes-tractions-semaine-3\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/entrainement-covid-pompes-tractions-semaine-3\\\/\",\"url\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/entrainement-covid-pompes-tractions-semaine-3\\\/\",\"name\":\"Entrainement COVID \u00e0 la maison, pompes, tractions, sem 3 - Grimpisme\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/entrainement-covid-pompes-tractions-semaine-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/entrainement-covid-pompes-tractions-semaine-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/training-1.jpg\",\"datePublished\":\"2021-02-01T09:16:50+00:00\",\"dateModified\":\"2021-04-30T12:33:01+00:00\",\"description\":\"Troisi\u00e8me semaine d\u2019entrainement COVID \u00e0 domicile. Apr\u00e8s les \u00e9tirements, les antagonistes, le gainage, place aux pompes et tractions.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/entrainement-covid-pompes-tractions-semaine-3\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.escalade.pro\\\/news\\\/entrainement-covid-pompes-tractions-semaine-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/entrainement-covid-pompes-tractions-semaine-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/training-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/training-1.jpg\",\"width\":924,\"height\":1100,\"caption\":\"entrainement escalade \u00e0 domicile\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/entrainement-covid-pompes-tractions-semaine-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrainement COVID \u00e0 la maison, pompes et tractions, semaine 3\\\/4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/\",\"name\":\"L&#039;Arqu\u00e9e Libre - Fred Vionnet entraineur\\\/moniteur escalade\",\"description\":\"Coaching et entrainement escalade. Buoux, C\u00e9\u00fcse et Fontainebleau.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/#organization\",\"name\":\"L&#039;Arqu\u00e9e Libre - Fred Vionnet entraineur\\\/moniteur escalade\",\"url\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo-wp-AL-avril-2026-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo-wp-AL-avril-2026-1.jpg\",\"width\":1955,\"height\":902,\"caption\":\"L&#039;Arqu\u00e9e Libre - Fred Vionnet entraineur\\\/moniteur escalade\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/grimpisme\\\/\",\"https:\\\/\\\/www.instagram.com\\\/grimpisme\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fred-vionnet-6284b96a\\\/\",\"https:\\\/\\\/fr.pinterest.com\\\/grimpisme\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@grimpisme\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/#\\\/schema\\\/person\\\/e0e0520aa48cfda56ae5406c2fe2caeb\",\"name\":\"Fred Vionnet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2f6c5fc695da895033dcd95afaa6aeda795d5122ab3a22a03e24aab7f3d96a6?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2f6c5fc695da895033dcd95afaa6aeda795d5122ab3a22a03e24aab7f3d96a6?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2f6c5fc695da895033dcd95afaa6aeda795d5122ab3a22a03e24aab7f3d96a6?s=96&d=blank&r=g\",\"caption\":\"Fred Vionnet\"},\"description\":\"Coach escalade en Haute Savoie. Pas contre une grande voie non plus. Mais on va \u00e0 C\u00e9\u00fcse, Fontainebleau, Buoux ou encore les Gorges du Verdon quand vous voulez.\",\"sameAs\":[\"http:\\\/\\\/www.grimpisme.com\",\"https:\\\/\\\/www.facebook.com\\\/fredCaillouXvionnet\",\"https:\\\/\\\/www.linkedin.com\\\/profile\\\/preview?vpa=pub&locale=fr_FR\",\"https:\\\/\\\/fr.pinterest.com\\\/grimpisme\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/grimpisme\",\"https:\\\/\\\/soundcloud.com\\\/fredvionnet\"],\"url\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/author\\\/fred\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrainement COVID \u00e0 la maison, pompes, tractions, sem 3 - Grimpisme","description":"Troisi\u00e8me semaine d\u2019entrainement COVID \u00e0 domicile. Apr\u00e8s les \u00e9tirements, les antagonistes, le gainage, place aux pompes et tractions.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.escalade.pro\/news\/entrainement-covid-pompes-tractions-semaine-3\/","og_locale":"fr_FR","og_type":"article","og_title":"Entrainement COVID \u00e0 la maison, pompes, tractions, sem 3 - Grimpisme","og_description":"Troisi\u00e8me semaine d\u2019entrainement COVID \u00e0 domicile. Apr\u00e8s les \u00e9tirements, les antagonistes, le gainage, place aux pompes et tractions.","og_url":"https:\/\/www.escalade.pro\/news\/entrainement-covid-pompes-tractions-semaine-3\/","og_site_name":"L&#039;Arqu\u00e9e Libre - Fred Vionnet entraineur\/moniteur escalade","article_publisher":"https:\/\/www.facebook.com\/grimpisme\/","article_author":"https:\/\/www.facebook.com\/fredCaillouXvionnet","article_published_time":"2021-02-01T09:16:50+00:00","article_modified_time":"2021-04-30T12:33:01+00:00","og_image":[{"width":924,"height":1100,"url":"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/training-1.jpg","type":"image\/jpeg"}],"author":"Fred Vionnet","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Fred Vionnet","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.escalade.pro\/news\/entrainement-covid-pompes-tractions-semaine-3\/#article","isPartOf":{"@id":"https:\/\/www.escalade.pro\/news\/entrainement-covid-pompes-tractions-semaine-3\/"},"author":{"name":"Fred Vionnet","@id":"https:\/\/www.escalade.pro\/news\/#\/schema\/person\/e0e0520aa48cfda56ae5406c2fe2caeb"},"headline":"Entrainement COVID \u00e0 la maison, pompes et tractions, semaine 3\/4","datePublished":"2021-02-01T09:16:50+00:00","dateModified":"2021-04-30T12:33:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.escalade.pro\/news\/entrainement-covid-pompes-tractions-semaine-3\/"},"wordCount":830,"commentCount":0,"publisher":{"@id":"https:\/\/www.escalade.pro\/news\/#organization"},"image":{"@id":"https:\/\/www.escalade.pro\/news\/entrainement-covid-pompes-tractions-semaine-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/training-1.jpg","keywords":["covid","domicile","entrainement","escalade"],"articleSection":["Conseils entrainement escalade","Escalade"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.escalade.pro\/news\/entrainement-covid-pompes-tractions-semaine-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.escalade.pro\/news\/entrainement-covid-pompes-tractions-semaine-3\/","url":"https:\/\/www.escalade.pro\/news\/entrainement-covid-pompes-tractions-semaine-3\/","name":"Entrainement COVID \u00e0 la maison, pompes, tractions, sem 3 - Grimpisme","isPartOf":{"@id":"https:\/\/www.escalade.pro\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.escalade.pro\/news\/entrainement-covid-pompes-tractions-semaine-3\/#primaryimage"},"image":{"@id":"https:\/\/www.escalade.pro\/news\/entrainement-covid-pompes-tractions-semaine-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/training-1.jpg","datePublished":"2021-02-01T09:16:50+00:00","dateModified":"2021-04-30T12:33:01+00:00","description":"Troisi\u00e8me semaine d\u2019entrainement COVID \u00e0 domicile. Apr\u00e8s les \u00e9tirements, les antagonistes, le gainage, place aux pompes et tractions.","breadcrumb":{"@id":"https:\/\/www.escalade.pro\/news\/entrainement-covid-pompes-tractions-semaine-3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.escalade.pro\/news\/entrainement-covid-pompes-tractions-semaine-3\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.escalade.pro\/news\/entrainement-covid-pompes-tractions-semaine-3\/#primaryimage","url":"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/training-1.jpg","contentUrl":"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/training-1.jpg","width":924,"height":1100,"caption":"entrainement escalade \u00e0 domicile"},{"@type":"BreadcrumbList","@id":"https:\/\/www.escalade.pro\/news\/entrainement-covid-pompes-tractions-semaine-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.escalade.pro\/news\/"},{"@type":"ListItem","position":2,"name":"Entrainement COVID \u00e0 la maison, pompes et tractions, semaine 3\/4"}]},{"@type":"WebSite","@id":"https:\/\/www.escalade.pro\/news\/#website","url":"https:\/\/www.escalade.pro\/news\/","name":"L&#039;Arqu\u00e9e Libre - Fred Vionnet entraineur\/moniteur escalade","description":"Coaching et entrainement escalade. Buoux, C\u00e9\u00fcse et Fontainebleau.","publisher":{"@id":"https:\/\/www.escalade.pro\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escalade.pro\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.escalade.pro\/news\/#organization","name":"L&#039;Arqu\u00e9e Libre - Fred Vionnet entraineur\/moniteur escalade","url":"https:\/\/www.escalade.pro\/news\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.escalade.pro\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2026\/04\/logo-wp-AL-avril-2026-1.jpg","contentUrl":"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2026\/04\/logo-wp-AL-avril-2026-1.jpg","width":1955,"height":902,"caption":"L&#039;Arqu\u00e9e Libre - Fred Vionnet entraineur\/moniteur escalade"},"image":{"@id":"https:\/\/www.escalade.pro\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grimpisme\/","https:\/\/www.instagram.com\/grimpisme\/","https:\/\/www.linkedin.com\/in\/fred-vionnet-6284b96a\/","https:\/\/fr.pinterest.com\/grimpisme\/","https:\/\/www.youtube.com\/@grimpisme"]},{"@type":"Person","@id":"https:\/\/www.escalade.pro\/news\/#\/schema\/person\/e0e0520aa48cfda56ae5406c2fe2caeb","name":"Fred Vionnet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a2f6c5fc695da895033dcd95afaa6aeda795d5122ab3a22a03e24aab7f3d96a6?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2f6c5fc695da895033dcd95afaa6aeda795d5122ab3a22a03e24aab7f3d96a6?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2f6c5fc695da895033dcd95afaa6aeda795d5122ab3a22a03e24aab7f3d96a6?s=96&d=blank&r=g","caption":"Fred Vionnet"},"description":"Coach escalade en Haute Savoie. Pas contre une grande voie non plus. Mais on va \u00e0 C\u00e9\u00fcse, Fontainebleau, Buoux ou encore les Gorges du Verdon quand vous voulez.","sameAs":["http:\/\/www.grimpisme.com","https:\/\/www.facebook.com\/fredCaillouXvionnet","https:\/\/www.linkedin.com\/profile\/preview?vpa=pub&locale=fr_FR","https:\/\/fr.pinterest.com\/grimpisme\/","https:\/\/www.youtube.com\/user\/grimpisme","https:\/\/soundcloud.com\/fredvionnet"],"url":"https:\/\/www.escalade.pro\/news\/author\/fred\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/training-1.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p68Rw6-5iN","jetpack-related-posts":[{"id":20324,"url":"https:\/\/www.escalade.pro\/news\/entrainement-covid-maison-semaine-2-4\/","url_meta":{"origin":20385,"position":0},"title":"Entrainement COVID \u00e0 la maison, gainage, semaine 2\/4","author":"Fred Vionnet","date":"22 janvier 2021","format":false,"excerpt":"Entrainement pour l'escalade \u00e0 domicile (COVID) semaine 2, travaillons le gainage. Rdv la semaine prochaine pour les pompes et les tractions.","rel":"","context":"Dans &quot;Conseils entrainement escalade&quot;","block_context":{"text":"Conseils entrainement escalade","link":"https:\/\/www.escalade.pro\/news\/category\/entrainement-escalade\/"},"img":{"alt_text":"entrainement escalade domicile","src":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/gainage-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/gainage-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/gainage-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/gainage-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/gainage-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":20247,"url":"https:\/\/www.escalade.pro\/news\/entrainement-maison-semaine-1-4\/","url_meta":{"origin":20385,"position":1},"title":"Entrainement COVID \u00e0 la maison, \u00e9tirements et antagonistes, semaine 1\/4","author":"Fred Vionnet","date":"15 janvier 2021","format":false,"excerpt":"Rendez-vous le lundi 25 janvier pour la deuxi\u00e8me semaine d\u2019entrainement, o\u00f9 nous travaillerons le gainage. Puis viendront le renforcement du haut du corps pour la troisi\u00e8me semaine, et la conti\/r\u00e9si pour la quatri\u00e8me.","rel":"","context":"Dans &quot;Conseils entrainement escalade&quot;","block_context":{"text":"Conseils entrainement escalade","link":"https:\/\/www.escalade.pro\/news\/category\/entrainement-escalade\/"},"img":{"alt_text":"materiel entrainement escalade","src":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/P1020818.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/P1020818.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/P1020818.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/P1020818.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/01\/P1020818.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":20569,"url":"https:\/\/www.escalade.pro\/news\/planifications-entrainement-domicile\/","url_meta":{"origin":20385,"position":2},"title":"COVID virus&#8230; 2 planifications d\u2019entrainement \u00e0 domicile pour survivre","author":"Fred Vionnet","date":"23 f\u00e9vrier 2021","format":false,"excerpt":"Deux exemples de planifications d'entrainement \u00e0 domicile, de 5 semaines, utilisant des exercices class\u00e9s en 4 familles.","rel":"","context":"Dans &quot;Conseils entrainement escalade&quot;","block_context":{"text":"Conseils entrainement escalade","link":"https:\/\/www.escalade.pro\/news\/category\/entrainement-escalade\/"},"img":{"alt_text":"entrainement escalade \u00e0 domicile","src":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/P1020862.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/P1020862.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/P1020862.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/P1020862.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":20488,"url":"https:\/\/www.escalade.pro\/news\/entrainement-covid-resi-conti-poutre-semaine-4\/","url_meta":{"origin":20385,"position":3},"title":"Entrainement COVID \u00e0 la maison, r\u00e9si et conti sur poutre, semaine 4\/4","author":"Fred Vionnet","date":"7 f\u00e9vrier 2021","format":false,"excerpt":"Quatri\u00e8me semaine d'entrainement anti-COVID \u00e0 domicile. R\u00e9si et conti sur poutre... ou sur tout support dont vous disposez.","rel":"","context":"Dans &quot;Conseils entrainement escalade&quot;","block_context":{"text":"Conseils entrainement escalade","link":"https:\/\/www.escalade.pro\/news\/category\/entrainement-escalade\/"},"img":{"alt_text":"poutre entrainement escalade","src":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/poutre-entrainement-escalade.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/poutre-entrainement-escalade.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/poutre-entrainement-escalade.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/poutre-entrainement-escalade.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/poutre-entrainement-escalade.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2021\/02\/poutre-entrainement-escalade.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":18982,"url":"https:\/\/www.escalade.pro\/news\/entrainement-confinement\/","url_meta":{"origin":20385,"position":4},"title":"Entrainement et confinement","author":"Fred Vionnet","date":"30 mars 2020","format":false,"excerpt":"Il s\u2019agit d\u2019entrainements de base en renforcement musculaire, avec \u00e9galement de la r\u00e9sistance longue. Vous y trouverez des entrainements au sol, avec un \u00e9lastique, puis des entrainements sur une barre \u00e0 tractions, sur une poutre, et m\u00eame sur un pan pour les plus chanceux.","rel":"","context":"Dans &quot;Conseils entrainement escalade&quot;","block_context":{"text":"Conseils entrainement escalade","link":"https:\/\/www.escalade.pro\/news\/category\/entrainement-escalade\/"},"img":{"alt_text":"entrainement escalade confinement","src":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2020\/03\/WhatsApp-Image-2020-03-30-at-13.18.32.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2020\/03\/WhatsApp-Image-2020-03-30-at-13.18.32.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2020\/03\/WhatsApp-Image-2020-03-30-at-13.18.32.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2020\/03\/WhatsApp-Image-2020-03-30-at-13.18.32.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2020\/03\/WhatsApp-Image-2020-03-30-at-13.18.32.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2020\/03\/WhatsApp-Image-2020-03-30-at-13.18.32.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":15533,"url":"https:\/\/www.escalade.pro\/news\/notions-entrainement-physique-escalade\/","url_meta":{"origin":20385,"position":5},"title":"Quelques notions d&rsquo;entrainement physique en escalade","author":"Fred Vionnet","date":"14 mars 2018","format":false,"excerpt":"Voici une synth\u00e8se de quelques notions de base concernant l\u2019entrainement physique en escalade. Il faut toujours avoir en t\u00eate que le physique ne fait pas tout, loin de l\u00e0. Le meilleur grimpeur est rarement le grimpeur le plus fort. Alors on n\u2019oublie pas la technique, la tactique, et surtout l\u2019envie!","rel":"","context":"Dans &quot;Conseils entrainement escalade&quot;","block_context":{"text":"Conseils entrainement escalade","link":"https:\/\/www.escalade.pro\/news\/category\/entrainement-escalade\/"},"img":{"alt_text":"entrainement escalade","src":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/03\/P1100428.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/03\/P1100428.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/03\/P1100428.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/03\/P1100428.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/posts\/20385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/comments?post=20385"}],"version-history":[{"count":67,"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/posts\/20385\/revisions"}],"predecessor-version":[{"id":20469,"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/posts\/20385\/revisions\/20469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/media\/20387"}],"wp:attachment":[{"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/media?parent=20385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/categories?post=20385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/tags?post=20385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}