{"id":17195,"date":"2018-11-25T08:14:09","date_gmt":"2018-11-25T07:14:09","guid":{"rendered":"https:\/\/www.escalade.pro\/news\/?p=17195"},"modified":"2019-06-20T12:55:28","modified_gmt":"2019-06-20T10:55:28","slug":"test-sac-dos-warthog-blue-ice","status":"publish","type":"post","link":"https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/","title":{"rendered":"Test sac \u00e0 dos Warthog 28L Blue Ice"},"content":{"rendered":"<p><a href=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/20180803_095132.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-17197\" src=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/20180803_095132-169x300.jpg\" alt=\"test sac dos warthog 28 blue ice\" width=\"169\" height=\"300\" srcset=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/20180803_095132-169x300.jpg 169w, https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/20180803_095132.jpg 450w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/a><\/p>\n<p><strong>J&rsquo;ai utilis\u00e9 le sac \u00e0 dos Warthog 28L de chez Blue Ice tr\u00e8s r\u00e9guli\u00e8rement depuis le mois d&rsquo;avril 2017. Quand je dis r\u00e9guli\u00e8rement, c&rsquo;est \u00e0 dire sur une grande majorit\u00e9 des sorties d&rsquo;<a href=\"https:\/\/www.escalade.pro\/news\/category\/alpinisme\/\">alpinisme<\/a> et de <a href=\"https:\/\/www.escalade.pro\/news\/category\/ski-freeride\/\">ski de rando<\/a> que j&rsquo;ai r\u00e9alis\u00e9es sur cette p\u00e9riode<\/strong> (\u00e7a en fait pas mal mais c&rsquo;est jamais assez non?). Plus que les articles du site web, l&rsquo;historique du compte <a href=\"https:\/\/www.instagram.com\/grimpisme\/\" rel=\"noopener noreferrer\" target=\"_blank\">Instagram de Grimpisme<\/a> est plus repr\u00e9sentatif. Les sorties se d\u00e9roulaient sur un ou deux jours, pas plus.<\/p>\n<p>Je n&rsquo;ai trouv\u00e9 qu&rsquo;un point faible \u00e0 ce sac \u00e0 dos. Le crochet de fermeture avait tendance \u00e0 sauter quand le sac n&rsquo;est pas assez plein. Ce probl\u00e8me a \u00e9t\u00e9 r\u00e9gl\u00e9 depuis avec l&rsquo;ajout d&rsquo;une boucle de fermeture plus basse. Ce qui permet de le compacter efficacement.<\/p>\n<p><u>J&rsquo;ai par contre appr\u00e9ci\u00e9 beaucoup de caract\u00e9ristiques du Warthog 26L:<\/u><br \/>\n&#8211; <strong>Simplicit\u00e9, on n&rsquo;est pas envahi par des gadgets inutiles et des sangles qui pendent de partout.<\/strong> M\u00eame si ce n&rsquo;est pas le plus l\u00e9ger des sacs \u00e0 dos pour ce volume.<br \/>\n&#8211; <strong>Robustesse incroyabl<\/strong>e, ce qui n&rsquo;est pas toujours le cas dans les produits montagne..<br \/>\n&#8211; <strong>Le confort de portage<\/strong> malgr\u00e9 la finesse de la sangle ventrale (y compris avec les skis sur le sac).<br \/>\n&#8211; <strong>Le porte-casque<\/strong>, tellement pratique, permettant d&rsquo;\u00e9viter un casque qui prend tellement de place dans le sac, o\u00f9 qui ballote sur le c\u00f4t\u00e9.<br \/>\n&#8211; <strong>L&rsquo;efficacit\u00e9 du syst\u00e8me de serrage et surtout de d\u00e9serrage du cordon de la poche principale<\/strong>. M\u00eame avec des gros gants c&rsquo;est facile et rapide.<br \/>\n&#8211; <strong>La polyvalence<\/strong> (alpinisme, rando, ski).<\/p>\n<p>Pas besoin d&rsquo;en dire plus, comme vous l&rsquo;avez compris <strong>j&rsquo;ai trouv\u00e9 mon sac \u00e0 dos id\u00e9al<\/strong>. Je ne me pause pas de questions quand je bouge pour un ou deux jours, je prends mon Warthog et c&rsquo;est tout.<\/p>\n<div id='gallery-1' class='gallery galleryid-17195 gallery-columns-3 gallery-size-colormag-featured-image'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a title=\"WhatsApp Image 2018-04-15 at 16.02.37\" href='https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/whatsapp-image-2018-04-15-at-16-02-37\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-04-15-at-16.02.37-800x445.jpeg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a title=\"test sac dos warthog 28 blue ice\" href='https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/20180730_142419-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/20180730_142419-800x445.jpg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"test sac dos warthog 28 blue ice\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a title=\"test sac dos warthog 28 blue ice\" href='https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/20180719_115959\/'><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"343\" src=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/20180719_115959.jpg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"test sac dos warthog 28 blue ice\" srcset=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/20180719_115959.jpg 600w, https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/20180719_115959-300x172.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a title=\"test sac dos warthog 28 blue ice\" href='https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/warthog-28l-pack-1\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/warthog-28l-pack-1-800x445.jpg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"test sac dos warthog 28 blue ice\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a title=\"test sac dos warthog 28 blue ice\" href='https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/warthog-28l-pack-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/warthog-28l-pack-2-800x445.jpg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"test sac dos warthog 28 blue ice\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a title=\"test sac dos warthog 28 blue ice\" href='https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/warthog-28l-pack\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/warthog-28l-pack-800x445.jpg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"test sac dos warthog 28 blue ice\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a title=\"test sac a dos blue ice\" href='https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/25552294_10155469541178173_1969182895402650151_n\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/25552294_10155469541178173_1969182895402650151_n-800x445.jpg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a title=\"test sac a dos blue ice\" href='https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/27982667_10155607048953173_8192571193247678941_o\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/27982667_10155607048953173_8192571193247678941_o-800x445.jpg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"test sac a dos blue ice\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a title=\"test sac a dos blue ice\" href='https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/warthog-28l-pack-fb\/'><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"445\" src=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/warthog-28l-pack-fb-595x445.jpg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"test sac a dos blue ice\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Voir la <a href=\"https:\/\/www.blueice.com\/fr\/sacs-a-dos\/81-warthog-28l-pack.html\" rel=\"noopener noreferrer\" target=\"_blank\">fiche technique du sac \u00e0 dos Warthog 28L sur le site web Blue Ice<\/a>.<\/p>\n<p><u>Les autres tests de mat\u00e9riel Blue Ice r\u00e9alis\u00e9s pr\u00e9c\u00e9demment:<\/u><br \/>\n&#8211; le <a href=\"https:\/\/www.escalade.pro\/news\/test-sac-warthog-26l-blue-ice\/\">sac \u00e0 dos Warthog 26<\/a> (un bestseller qui n&rsquo;est plus produit)<br \/>\n&#8211; le <a href=\"https:\/\/www.escalade.pro\/news\/sac-koala-blue-ice\/\">sac \u00e0 corde Koala<\/a> (qui a \u00e9volu\u00e9 depuis).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pas besoin d\u2019en dire plus, comme vous l\u2019avez compris j\u2019ai trouv\u00e9 mon sac \u00e0 dos id\u00e9al. Je ne me pause pas de questions quand je bouge pour un ou deux jours, je prends mon Warthog et c\u2019est tout.<\/p>\n","protected":false},"author":1,"featured_media":17197,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[5,4,8,3],"tags":[50,48,51,47,52,46,49],"class_list":["post-17195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alpinisme","category-escalade","category-ski-freeride","category-tests-materiel","tag-alpinisme","tag-blue-ice","tag-montagne","tag-sac-a-dos","tag-ski","tag-tes-materiel","tag-warthog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Test mat\u00e9riel: sac \u00e0 dos Warthog 26L Blue Ice - Grimpisme<\/title>\n<meta name=\"description\" content=\"Comme vous l\u2019avez compris j\u2019ai trouv\u00e9 mon sac \u00e0 dos id\u00e9al. Je ne me pause pas de questions quand je bouge pour un ou deux jours, je prends mon Warthog.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Test mat\u00e9riel: sac \u00e0 dos Warthog 26L Blue Ice - Grimpisme\" \/>\n<meta property=\"og:description\" content=\"Comme vous l\u2019avez compris j\u2019ai trouv\u00e9 mon sac \u00e0 dos id\u00e9al. Je ne me pause pas de questions quand je bouge pour un ou deux jours, je prends mon Warthog.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/\" \/>\n<meta property=\"og:site_name\" content=\"L&#039;Arqu\u00e9e Libre - Fred Vionnet entraineur\/moniteur escalade\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grimpisme\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/fredCaillouXvionnet\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-25T07:14:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-20T10:55:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/20180803_095132.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fred Vionnet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fred Vionnet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/test-sac-dos-warthog-blue-ice\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/test-sac-dos-warthog-blue-ice\\\/\"},\"author\":{\"name\":\"Fred Vionnet\",\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/#\\\/schema\\\/person\\\/e0e0520aa48cfda56ae5406c2fe2caeb\"},\"headline\":\"Test sac \u00e0 dos Warthog 28L Blue Ice\",\"datePublished\":\"2018-11-25T07:14:09+00:00\",\"dateModified\":\"2019-06-20T10:55:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/test-sac-dos-warthog-blue-ice\\\/\"},\"wordCount\":368,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/test-sac-dos-warthog-blue-ice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/20180803_095132.jpg\",\"keywords\":[\"alpinisme\",\"blue ice\",\"montagne\",\"sac \u00e0 dos\",\"ski\",\"tes mat\u00e9riel\",\"warthog\"],\"articleSection\":[\"Alpinisme\",\"Escalade\",\"Ski de rando et freeride\",\"Tests mat\u00e9riel, nouveaut\u00e9s et lectures\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.escalade.pro\\\/news\\\/test-sac-dos-warthog-blue-ice\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/test-sac-dos-warthog-blue-ice\\\/\",\"url\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/test-sac-dos-warthog-blue-ice\\\/\",\"name\":\"Test mat\u00e9riel: sac \u00e0 dos Warthog 26L Blue Ice - Grimpisme\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/test-sac-dos-warthog-blue-ice\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/test-sac-dos-warthog-blue-ice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/20180803_095132.jpg\",\"datePublished\":\"2018-11-25T07:14:09+00:00\",\"dateModified\":\"2019-06-20T10:55:28+00:00\",\"description\":\"Comme vous l\u2019avez compris j\u2019ai trouv\u00e9 mon sac \u00e0 dos id\u00e9al. Je ne me pause pas de questions quand je bouge pour un ou deux jours, je prends mon Warthog.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/test-sac-dos-warthog-blue-ice\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.escalade.pro\\\/news\\\/test-sac-dos-warthog-blue-ice\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/test-sac-dos-warthog-blue-ice\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/20180803_095132.jpg\",\"contentUrl\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/20180803_095132.jpg\",\"width\":450,\"height\":800,\"caption\":\"test sac dos warthog 28 blue ice\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/test-sac-dos-warthog-blue-ice\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Test sac \u00e0 dos Warthog 28L Blue Ice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/\",\"name\":\"L&#039;Arqu\u00e9e Libre - Fred Vionnet entraineur\\\/moniteur escalade\",\"description\":\"Coaching et entrainement escalade. Buoux, C\u00e9\u00fcse et Fontainebleau.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/#organization\",\"name\":\"L&#039;Arqu\u00e9e Libre - Fred Vionnet entraineur\\\/moniteur escalade\",\"url\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo-wp-AL-avril-2026-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo-wp-AL-avril-2026-1.jpg\",\"width\":1955,\"height\":902,\"caption\":\"L&#039;Arqu\u00e9e Libre - Fred Vionnet entraineur\\\/moniteur escalade\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/grimpisme\\\/\",\"https:\\\/\\\/www.instagram.com\\\/grimpisme\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fred-vionnet-6284b96a\\\/\",\"https:\\\/\\\/fr.pinterest.com\\\/grimpisme\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@grimpisme\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/#\\\/schema\\\/person\\\/e0e0520aa48cfda56ae5406c2fe2caeb\",\"name\":\"Fred Vionnet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2f6c5fc695da895033dcd95afaa6aeda795d5122ab3a22a03e24aab7f3d96a6?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2f6c5fc695da895033dcd95afaa6aeda795d5122ab3a22a03e24aab7f3d96a6?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2f6c5fc695da895033dcd95afaa6aeda795d5122ab3a22a03e24aab7f3d96a6?s=96&d=blank&r=g\",\"caption\":\"Fred Vionnet\"},\"description\":\"Coach escalade en Haute Savoie. Pas contre une grande voie non plus. Mais on va \u00e0 C\u00e9\u00fcse, Fontainebleau, Buoux ou encore les Gorges du Verdon quand vous voulez.\",\"sameAs\":[\"http:\\\/\\\/www.grimpisme.com\",\"https:\\\/\\\/www.facebook.com\\\/fredCaillouXvionnet\",\"https:\\\/\\\/www.linkedin.com\\\/profile\\\/preview?vpa=pub&locale=fr_FR\",\"https:\\\/\\\/fr.pinterest.com\\\/grimpisme\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/grimpisme\",\"https:\\\/\\\/soundcloud.com\\\/fredvionnet\"],\"url\":\"https:\\\/\\\/www.escalade.pro\\\/news\\\/author\\\/fred\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Test mat\u00e9riel: sac \u00e0 dos Warthog 26L Blue Ice - Grimpisme","description":"Comme vous l\u2019avez compris j\u2019ai trouv\u00e9 mon sac \u00e0 dos id\u00e9al. Je ne me pause pas de questions quand je bouge pour un ou deux jours, je prends mon Warthog.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/","og_locale":"fr_FR","og_type":"article","og_title":"Test mat\u00e9riel: sac \u00e0 dos Warthog 26L Blue Ice - Grimpisme","og_description":"Comme vous l\u2019avez compris j\u2019ai trouv\u00e9 mon sac \u00e0 dos id\u00e9al. Je ne me pause pas de questions quand je bouge pour un ou deux jours, je prends mon Warthog.","og_url":"https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/","og_site_name":"L&#039;Arqu\u00e9e Libre - Fred Vionnet entraineur\/moniteur escalade","article_publisher":"https:\/\/www.facebook.com\/grimpisme\/","article_author":"https:\/\/www.facebook.com\/fredCaillouXvionnet","article_published_time":"2018-11-25T07:14:09+00:00","article_modified_time":"2019-06-20T10:55:28+00:00","og_image":[{"width":450,"height":800,"url":"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/20180803_095132.jpg","type":"image\/jpeg"}],"author":"Fred Vionnet","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Fred Vionnet","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/#article","isPartOf":{"@id":"https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/"},"author":{"name":"Fred Vionnet","@id":"https:\/\/www.escalade.pro\/news\/#\/schema\/person\/e0e0520aa48cfda56ae5406c2fe2caeb"},"headline":"Test sac \u00e0 dos Warthog 28L Blue Ice","datePublished":"2018-11-25T07:14:09+00:00","dateModified":"2019-06-20T10:55:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/"},"wordCount":368,"commentCount":0,"publisher":{"@id":"https:\/\/www.escalade.pro\/news\/#organization"},"image":{"@id":"https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/20180803_095132.jpg","keywords":["alpinisme","blue ice","montagne","sac \u00e0 dos","ski","tes mat\u00e9riel","warthog"],"articleSection":["Alpinisme","Escalade","Ski de rando et freeride","Tests mat\u00e9riel, nouveaut\u00e9s et lectures"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/","url":"https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/","name":"Test mat\u00e9riel: sac \u00e0 dos Warthog 26L Blue Ice - Grimpisme","isPartOf":{"@id":"https:\/\/www.escalade.pro\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/#primaryimage"},"image":{"@id":"https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/20180803_095132.jpg","datePublished":"2018-11-25T07:14:09+00:00","dateModified":"2019-06-20T10:55:28+00:00","description":"Comme vous l\u2019avez compris j\u2019ai trouv\u00e9 mon sac \u00e0 dos id\u00e9al. Je ne me pause pas de questions quand je bouge pour un ou deux jours, je prends mon Warthog.","breadcrumb":{"@id":"https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/#primaryimage","url":"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/20180803_095132.jpg","contentUrl":"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/20180803_095132.jpg","width":450,"height":800,"caption":"test sac dos warthog 28 blue ice"},{"@type":"BreadcrumbList","@id":"https:\/\/www.escalade.pro\/news\/test-sac-dos-warthog-blue-ice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.escalade.pro\/news\/"},{"@type":"ListItem","position":2,"name":"Test sac \u00e0 dos Warthog 28L Blue Ice"}]},{"@type":"WebSite","@id":"https:\/\/www.escalade.pro\/news\/#website","url":"https:\/\/www.escalade.pro\/news\/","name":"L&#039;Arqu\u00e9e Libre - Fred Vionnet entraineur\/moniteur escalade","description":"Coaching et entrainement escalade. Buoux, C\u00e9\u00fcse et Fontainebleau.","publisher":{"@id":"https:\/\/www.escalade.pro\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escalade.pro\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.escalade.pro\/news\/#organization","name":"L&#039;Arqu\u00e9e Libre - Fred Vionnet entraineur\/moniteur escalade","url":"https:\/\/www.escalade.pro\/news\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.escalade.pro\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2026\/04\/logo-wp-AL-avril-2026-1.jpg","contentUrl":"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2026\/04\/logo-wp-AL-avril-2026-1.jpg","width":1955,"height":902,"caption":"L&#039;Arqu\u00e9e Libre - Fred Vionnet entraineur\/moniteur escalade"},"image":{"@id":"https:\/\/www.escalade.pro\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grimpisme\/","https:\/\/www.instagram.com\/grimpisme\/","https:\/\/www.linkedin.com\/in\/fred-vionnet-6284b96a\/","https:\/\/fr.pinterest.com\/grimpisme\/","https:\/\/www.youtube.com\/@grimpisme"]},{"@type":"Person","@id":"https:\/\/www.escalade.pro\/news\/#\/schema\/person\/e0e0520aa48cfda56ae5406c2fe2caeb","name":"Fred Vionnet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a2f6c5fc695da895033dcd95afaa6aeda795d5122ab3a22a03e24aab7f3d96a6?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2f6c5fc695da895033dcd95afaa6aeda795d5122ab3a22a03e24aab7f3d96a6?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2f6c5fc695da895033dcd95afaa6aeda795d5122ab3a22a03e24aab7f3d96a6?s=96&d=blank&r=g","caption":"Fred Vionnet"},"description":"Coach escalade en Haute Savoie. Pas contre une grande voie non plus. Mais on va \u00e0 C\u00e9\u00fcse, Fontainebleau, Buoux ou encore les Gorges du Verdon quand vous voulez.","sameAs":["http:\/\/www.grimpisme.com","https:\/\/www.facebook.com\/fredCaillouXvionnet","https:\/\/www.linkedin.com\/profile\/preview?vpa=pub&locale=fr_FR","https:\/\/fr.pinterest.com\/grimpisme\/","https:\/\/www.youtube.com\/user\/grimpisme","https:\/\/soundcloud.com\/fredvionnet"],"url":"https:\/\/www.escalade.pro\/news\/author\/fred\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/11\/20180803_095132.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p68Rw6-4tl","jetpack-related-posts":[{"id":7594,"url":"https:\/\/www.escalade.pro\/news\/test-sac-warthog-26l-blue-ice\/","url_meta":{"origin":17195,"position":0},"title":"Test sac \u00e0 dos Warthog 26L Blue Ice","author":"Fred Vionnet","date":"9 f\u00e9vrier 2016","format":false,"excerpt":"Apr\u00e8s de nombreuses utilisations du sac Warthog 26L Blue Ice (voir la fiche technique) en alpinisme et grandes voies sur 2014 et 2015, je pense \u00eatre en mesure de vous donner un avis qui tient la route sur la qualit\u00e9 de cet article. On va commencer par le seul point\u2026","rel":"","context":"Dans &quot;Tests mat\u00e9riel, nouveaut\u00e9s et lectures&quot;","block_context":{"text":"Tests mat\u00e9riel, nouveaut\u00e9s et lectures","link":"https:\/\/www.escalade.pro\/news\/category\/tests-materiel\/"},"img":{"alt_text":"sac \u00e0 dos warthog blue ice","src":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2016\/02\/backpack-Warthog26_01-300x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12259,"url":"https:\/\/www.escalade.pro\/news\/test-baudrier-choucasblue-ice\/","url_meta":{"origin":17195,"position":1},"title":"Test: baudrier Choucas III Blue Ice","author":"Fred Vionnet","date":"30 ao\u00fbt 2016","format":false,"excerpt":"Apr\u00e8s un hiver et une saison estivale d'utilisation du baudrier Choucas III de Blue Ice, voici mon avis sur ce harnais l\u00e9ger con\u00e7u pour la pratique du ski et de l'alpinisme (voir fiche produit). Voil\u00e0 un baudrier tr\u00e8s l\u00e9ger (180g en taille M), qui se range dans une petite housse\u2026","rel":"","context":"Dans &quot;Alpinisme&quot;","block_context":{"text":"Alpinisme","link":"https:\/\/www.escalade.pro\/news\/category\/alpinisme\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2016\/07\/IMG_1300.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2016\/07\/IMG_1300.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2016\/07\/IMG_1300.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2016\/07\/IMG_1300.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15334,"url":"https:\/\/www.escalade.pro\/news\/ski-envers-aiguilles-rouges\/","url_meta":{"origin":17195,"position":2},"title":"Excellent ski \u00e0 l&rsquo;envers des Aiguilles Rouges, pourquoi en dire plus?","author":"Fred Vionnet","date":"16 janvier 2018","format":false,"excerpt":"Alors pourquoi ne plus publier de sorties de ski de rando sur C2C? Une fois de plus soyons clair: c\u2019est par \u00e9go\u00efsme! J\u2019ai longtemps appr\u00e9ci\u00e9 cette id\u00e9e de communaut\u00e9 et de partage, mais entre le fort d\u00e9veloppement du ski de randonn\u00e9e, de la freerando...","rel":"","context":"Dans &quot;Coups de gueule&quot;","block_context":{"text":"Coups de gueule","link":"https:\/\/www.escalade.pro\/news\/category\/coup-de-gueule\/"},"img":{"alt_text":"ski randonn\u00e9e envers aiguilles rouges","src":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/01\/Capture-d%E2%80%99e%CC%81cran-2018-01-15-a%CC%80-16.35.47.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/01\/Capture-d%E2%80%99e%CC%81cran-2018-01-15-a%CC%80-16.35.47.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/01\/Capture-d%E2%80%99e%CC%81cran-2018-01-15-a%CC%80-16.35.47.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2018\/01\/Capture-d%E2%80%99e%CC%81cran-2018-01-15-a%CC%80-16.35.47.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3336,"url":"https:\/\/www.escalade.pro\/news\/sacs-blue-ice\/","url_meta":{"origin":17195,"position":3},"title":"Blue Ice backpacksSacs Blue Ice","author":"Fred Vionnet","date":"19 septembre 2014","format":false,"excerpt":"I'm happy to work with Blue Ice as we're about to be neighbours (they'll moove to les Houches on december) and as they bags are very interesting. Check out Warthog 26, Koala and Octopuss. Quelques nouveaux produits Blue Ice sont dispos sur le magasin en ligne. C'est sympa de bosser\u2026","rel":"","context":"Dans &quot;Alpinisme&quot;","block_context":{"text":"Alpinisme","link":"https:\/\/www.escalade.pro\/news\/category\/alpinisme\/"},"img":{"alt_text":"blueice sac \u00e0 dos","src":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2014\/09\/blueice-265x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4317,"url":"https:\/\/www.escalade.pro\/news\/test-ski-h112-zag\/","url_meta":{"origin":17195,"position":4},"title":"Test ski H112 ZAG","author":"Fred Vionnet","date":"13 f\u00e9vrier 2015","format":false,"excerpt":"J\u2019ai plusieurs tests de mat\u00e9riel de grimpe\/alpinisme sur le feu, mais une fois n\u2019est pas coutume, je vais vous parler de ski. Je suis pass\u00e9 au Ski Pro Shop de ZAG \u00e0 Argenti\u00e8re o\u00f9 il est possible de tester leurs skis. Vu les conditions de neige dure du moment, les\u2026","rel":"","context":"Dans &quot;Ski de rando et freeride&quot;","block_context":{"text":"Ski de rando et freeride","link":"https:\/\/www.escalade.pro\/news\/category\/ski-freeride\/"},"img":{"alt_text":"h112 ski zag","src":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2015\/02\/h112.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2015\/02\/h112.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.escalade.pro\/news\/wp-content\/uploads\/2015\/02\/h112.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":11632,"url":"https:\/\/www.escalade.pro\/news\/test-sac-dos-triolet-30-millet\/","url_meta":{"origin":17195,"position":5},"title":"Test sac \u00e0 dos Triolet 30 Millet","author":"Fred Vionnet","date":"15 avril 2012","format":false,"excerpt":"Depuis quelques semaines nous proposons le sac \u00e0 dos Triolet 30 Millet dans le magasin en ligne. Millet (voir la page de leur site) communique sur ce sac \u00e0 dos en ce mois d'avril, \u00e9tant donn\u00e9 qu'il s'agit d'un nouveau mod\u00e8le, un petit test s'impose. Millet le qualifie de \"sac\u2026","rel":"","context":"Dans &quot;Tests mat\u00e9riel, nouveaut\u00e9s et lectures&quot;","block_context":{"text":"Tests mat\u00e9riel, nouveaut\u00e9s et lectures","link":"https:\/\/www.escalade.pro\/news\/category\/tests-materiel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/posts\/17195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/comments?post=17195"}],"version-history":[{"count":20,"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/posts\/17195\/revisions"}],"predecessor-version":[{"id":18095,"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/posts\/17195\/revisions\/18095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/media\/17197"}],"wp:attachment":[{"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/media?parent=17195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/categories?post=17195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escalade.pro\/news\/wp-json\/wp\/v2\/tags?post=17195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}